{"id":6492,"date":"2019-10-15T16:36:20","date_gmt":"2019-10-15T14:36:20","guid":{"rendered":"http:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg"},"modified":"2019-10-15T16:36:20","modified_gmt":"2019-10-15T14:36:20","slug":"passera-sobre-tram-que-connecta-bassa-1-i-2-3","status":"inherit","type":"attachment","link":"https:\/\/lifealnus.eu\/en\/working-in-gallissa-pools\/passera-sobre-tram-que-connecta-bassa-1-i-2-3\/","title":{"rendered":"passera sobre tram que connecta bassa 1 i 2"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_links_to":"","_links_to_target":""},"class_list":["post-6492","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>passera sobre tram que connecta bassa 1 i 2 - LIFE Alnus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"passera sobre tram que connecta bassa 1 i 2 - LIFE Alnus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg\" \/>\n<meta property=\"og:site_name\" content=\"LIFE Alnus\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"777\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifealnus.eu\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg\",\"url\":\"https:\\\/\\\/lifealnus.eu\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg\",\"name\":\"passera sobre tram que connecta bassa 1 i 2 - LIFE Alnus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifealnus.eu\\\/#website\"},\"datePublished\":\"2019-10-15T14:36:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifealnus.eu\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lifealnus.eu\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifealnus.eu\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/lifealnus.eu\\\/en\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Working in Galliss\u00e0 pools\",\"item\":\"https:\\\/\\\/lifealnus.eu\\\/en\\\/working-in-gallissa-pools\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"passera sobre tram que connecta bassa 1 i 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifealnus.eu\\\/#website\",\"url\":\"https:\\\/\\\/lifealnus.eu\\\/\",\"name\":\"LIFE Alnus\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifealnus.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"passera sobre tram que connecta bassa 1 i 2 - LIFE Alnus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg","og_locale":"en_US","og_type":"article","og_title":"passera sobre tram que connecta bassa 1 i 2 - LIFE Alnus","og_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg","og_site_name":"LIFE Alnus","og_image":[{"width":1600,"height":777,"url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg","url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg","name":"passera sobre tram que connecta bassa 1 i 2 - LIFE Alnus","isPartOf":{"@id":"https:\/\/lifealnus.eu\/#website"},"datePublished":"2019-10-15T14:36:20+00:00","breadcrumb":{"@id":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/lifealnus.eu\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"Working in Galliss\u00e0 pools","item":"https:\/\/lifealnus.eu\/en\/working-in-gallissa-pools\/"},{"@type":"ListItem","position":3,"name":"passera sobre tram que connecta bassa 1 i 2"}]},{"@type":"WebSite","@id":"https:\/\/lifealnus.eu\/#website","url":"https:\/\/lifealnus.eu\/","name":"LIFE Alnus","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifealnus.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"146\" src=\"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-300x146.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-300x146.jpeg 300w, https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-768x373.jpeg 768w, https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-1024x497.jpeg 1024w, https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-810x393.jpeg 810w, https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-560x272.jpeg 560w, https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-1110x539.jpeg 1110w, https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-120x58.jpeg 120w, https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":777,"file":"2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg","sizes":{"thumbnail":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-150x150.jpeg"},"medium":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-300x146.jpeg","width":300,"height":146,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-300x146.jpeg"},"medium_large":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-768x373.jpeg","width":768,"height":373,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-768x373.jpeg"},"large":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-1024x497.jpeg","width":1024,"height":497,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-1024x497.jpeg"},"project-thumbnail":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-810x393.jpeg","width":810,"height":393,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-810x393.jpeg"},"project-thumbnail-masonry":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-560x272.jpeg","width":560,"height":272,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-560x272.jpeg"},"project-thumbnail-tiny":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-78x78.jpeg","width":78,"height":78,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-78x78.jpeg"},"project-thumbnail-medium":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-560x384.jpeg","width":560,"height":384,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-560x384.jpeg"},"project-thumbnail-large":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-1110x539.jpeg","width":1110,"height":539,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-1110x539.jpeg"},"project-thumbnail-related":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-560x370.jpeg","width":560,"height":370,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-560x370.jpeg"},"event-thumb":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-560x370.jpeg","width":560,"height":370,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-560x370.jpeg"},"event-category":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-155x155.jpeg","width":155,"height":155,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-155x155.jpeg"},"event-full":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-810x393.jpeg","width":810,"height":393,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-810x393.jpeg"},"post-thumbnail":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-810x393.jpeg","width":810,"height":393,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-810x393.jpeg"},"thumbnail-medium":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-560x395.jpeg","width":560,"height":395,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-560x395.jpeg"},"thumbnail-large":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-1100x439.jpeg","width":1100,"height":439,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-1100x439.jpeg"},"thumbnail-related":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-560x370.jpeg","width":560,"height":370,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-560x370.jpeg"},"thumbnail-masonry":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-560x272.jpeg","width":560,"height":272,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-560x272.jpeg"},"thumbnail-megamenu":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-240x158.jpeg","width":240,"height":158,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-240x158.jpeg"},"admin-thumbnail":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-120x58.jpeg","width":120,"height":58,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-120x58.jpeg"},"thumbnail-widget":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-50x50.jpeg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-50x50.jpeg"},"45df0767-thumbnail":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2-160x96.jpeg","width":160,"height":96,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2-160x96.jpeg"},"full":{"file":"passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg","width":1600,"height":777,"mime_type":"image\/jpeg","source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":6494,"source_url":"https:\/\/lifealnus.eu\/wp-content\/uploads\/2019\/10\/passera-sobre-tram-que-connecta-bassa-1-i-2-2.jpeg","_links":{"self":[{"href":"https:\/\/lifealnus.eu\/en\/wp-json\/wp\/v2\/media\/6492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifealnus.eu\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/lifealnus.eu\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/lifealnus.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":6494,"href":"https:\/\/lifealnus.eu\/en\/wp-json\/wp\/v2\/posts\/6494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}